{"id":2940,"date":"2020-03-28T14:11:25","date_gmt":"2020-03-28T14:11:25","guid":{"rendered":"https:\/\/rauwers.servicecompany.be\/?p=2940"},"modified":"2023-05-28T17:00:03","modified_gmt":"2023-05-28T17:00:03","slug":"een-voertuig-onderscheppen","status":"publish","type":"post","link":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/","title":{"rendered":"Een voertuig onderscheppen"},"content":{"rendered":"<p>[av_textblock size=&#8221; font_color=&#8221; color=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; av_uid=&#8217;av-k88m5ezk&#8217; id=&#8221; custom_class=&#8221; admin_preview_bg=&#8221;]<br \/>\n<img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-2738\" src=\"https:\/\/rauwers.be\/wp-content\/uploads\/2020\/03\/art-TS-famenne.jpg\" alt=\"\" width=\"1280\" height=\"800\"><\/p>\n<h2>De communicatie met de gebruiker vereenvoudigen<\/h2>\n<p><strong>Rudy Fagnant,<\/strong> 1ste politie-inspecteur in de politiezone Famenne-Ardenne<\/p>\n<hr class=\"break\">\n<p>&#8220;Vroeger moesten we om een voertuig te onderschep- pen onze arm uit het raam steken, eventueel met een lichtkegel. We hebben nu al 5 jaar een Traffic Storm en sindsdien is alles veel eenvoudiger, effici\u00ebnter en ook veel veiliger geworden. Het tekstbord wordt ingeschakeld tijdens het rijden. Het is verlicht, de letters zijn heel groot en dus goed leesbaar, zelfs in de verte.<\/p>\n<p>De montage op het dak is een groot voordeel voor vracht- wagens, die het daardoor probleemloos kunnen lezen, terwijl onze gebaren door het raam vaak onopgemerkt bleven!<\/p>\n<p>Bovendien is het meertalig zodat we op basis van de nummerplaat meteen kunnen kiezen in welke&nbsp;taal we de tekst weergeven.<\/p>\n<p>Ook wanneer we met de Luxemburgse douane samenwerken, tonen we bij- voorbeeld de boodschap \u201cVolg ons\u201d tot aan een ruime parking om de vereiste controle uit te voeren.&#8221;<br \/>\n[\/av_textblock]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[av_textblock size=&#8221; font_color=&#8221; color=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; av_uid=&#8217;av-k88m5ezk&#8217; id=&#8221; custom_class=&#8221; admin_preview_bg=&#8221;] De communicatie met de gebruiker vereenvoudigen Rudy Fagnant, 1ste politie-inspecteur in de politiezone Famenne-Ardenne &#8220;Vroeger moesten we om een voertuig te onderschep- pen onze arm uit het raam steken, eventueel met een lichtkegel. We hebben nu al 5 jaar een Traffic Storm en sindsdien [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":15832,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[124,26],"tags":[],"class_list":["post-2940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles","category-artikels"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Smart solutions for mobility and road safety | Een voertuig onderscheppen\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Support\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"nl_NL\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Rauwers Belgium | Smart solutions for mobility and road safety.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Een voertuig onderscheppen | Rauwers Belgium\" \/>\n\t\t<meta property=\"og:description\" content=\"Smart solutions for mobility and road safety | Een voertuig onderscheppen\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/rauwers.be\/wp-content\/uploads\/2021\/08\/logo_rauwers.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/rauwers.be\/wp-content\/uploads\/2021\/08\/logo_rauwers.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-03-28T14:11:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-28T17:00:03+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RauwersBelgium\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Een voertuig onderscheppen | Rauwers Belgium\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Smart solutions for mobility and road safety | Een voertuig onderscheppen\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/rauwers.be\/wp-content\/uploads\/2021\/08\/logo_rauwers.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#article\",\"name\":\"Een voertuig onderscheppen | Rauwers Belgium\",\"headline\":\"Een voertuig onderscheppen\",\"author\":{\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/author\\\/supportrauwerseurope-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/rauwers.be\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/art-TS-famenne.jpg\",\"width\":1280,\"height\":800},\"datePublished\":\"2020-03-28T14:11:25+00:00\",\"dateModified\":\"2023-05-28T17:00:03+00:00\",\"inLanguage\":\"nl-NL\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#webpage\"},\"articleSection\":\"Articles, Artikels\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/category\\\/artikels\\\/#listItem\",\"name\":\"Artikels\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/category\\\/artikels\\\/#listItem\",\"position\":2,\"name\":\"Artikels\",\"item\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/category\\\/artikels\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#listItem\",\"name\":\"Een voertuig onderscheppen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#listItem\",\"position\":3,\"name\":\"Een voertuig onderscheppen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/category\\\/artikels\\\/#listItem\",\"name\":\"Artikels\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/#organization\",\"name\":\"Rauwers Belgium\",\"description\":\"Smart solutions for mobility and road safety.\",\"url\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/\",\"telephone\":\"+3222400900\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/wordpress-896047-3530020.cloudwaysapps.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/rauwers_logo_3x.png\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RauwersBelgium\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rauwerseurope\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rauwers\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/author\\\/supportrauwerseurope-com\\\/#author\",\"url\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/author\\\/supportrauwerseurope-com\\\/\",\"name\":\"Support\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9aaa50a34da4c12b316737e999deebfb55d3e9e45ab80ab39d449a05e14a1fd?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Support\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#webpage\",\"url\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/\",\"name\":\"Een voertuig onderscheppen | Rauwers Belgium\",\"description\":\"Smart solutions for mobility and road safety | Een voertuig onderscheppen\",\"inLanguage\":\"nl-NL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/author\\\/supportrauwerseurope-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/author\\\/supportrauwerseurope-com\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/rauwers.be\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/art-TS-famenne.jpg\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#mainImage\",\"width\":1280,\"height\":800},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/een-voertuig-onderscheppen\\\/#mainImage\"},\"datePublished\":\"2020-03-28T14:11:25+00:00\",\"dateModified\":\"2023-05-28T17:00:03+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/\",\"name\":\"Rauwers Belgium\",\"description\":\"Smart solutions for mobility and road safety.\",\"inLanguage\":\"nl-NL\",\"publisher\":{\"@id\":\"https:\\\/\\\/rauwers.be\\\/nl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Een voertuig onderscheppen | Rauwers Belgium","description":"Smart solutions for mobility and road safety | Een voertuig onderscheppen","canonical_url":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#article","name":"Een voertuig onderscheppen | Rauwers Belgium","headline":"Een voertuig onderscheppen","author":{"@id":"https:\/\/rauwers.be\/nl\/author\/supportrauwerseurope-com\/#author"},"publisher":{"@id":"https:\/\/rauwers.be\/nl\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/rauwers.be\/wp-content\/uploads\/2020\/03\/art-TS-famenne.jpg","width":1280,"height":800},"datePublished":"2020-03-28T14:11:25+00:00","dateModified":"2023-05-28T17:00:03+00:00","inLanguage":"nl-NL","mainEntityOfPage":{"@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#webpage"},"isPartOf":{"@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#webpage"},"articleSection":"Articles, Artikels"},{"@type":"BreadcrumbList","@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/rauwers.be\/nl\/#listItem","position":1,"name":"Accueil","item":"https:\/\/rauwers.be\/nl\/","nextItem":{"@type":"ListItem","@id":"https:\/\/rauwers.be\/nl\/category\/artikels\/#listItem","name":"Artikels"}},{"@type":"ListItem","@id":"https:\/\/rauwers.be\/nl\/category\/artikels\/#listItem","position":2,"name":"Artikels","item":"https:\/\/rauwers.be\/nl\/category\/artikels\/","nextItem":{"@type":"ListItem","@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#listItem","name":"Een voertuig onderscheppen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/rauwers.be\/nl\/#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#listItem","position":3,"name":"Een voertuig onderscheppen","previousItem":{"@type":"ListItem","@id":"https:\/\/rauwers.be\/nl\/category\/artikels\/#listItem","name":"Artikels"}}]},{"@type":"Organization","@id":"https:\/\/rauwers.be\/nl\/#organization","name":"Rauwers Belgium","description":"Smart solutions for mobility and road safety.","url":"https:\/\/rauwers.be\/nl\/","telephone":"+3222400900","logo":{"@type":"ImageObject","url":"https:\/\/wordpress-896047-3530020.cloudwaysapps.com\/wp-content\/uploads\/2020\/10\/rauwers_logo_3x.png","@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#organizationLogo"},"image":{"@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/RauwersBelgium\/","https:\/\/www.instagram.com\/rauwerseurope\/","https:\/\/www.linkedin.com\/company\/rauwers\/"]},{"@type":"Person","@id":"https:\/\/rauwers.be\/nl\/author\/supportrauwerseurope-com\/#author","url":"https:\/\/rauwers.be\/nl\/author\/supportrauwerseurope-com\/","name":"Support","image":{"@type":"ImageObject","@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c9aaa50a34da4c12b316737e999deebfb55d3e9e45ab80ab39d449a05e14a1fd?s=96&d=mm&r=g","width":96,"height":96,"caption":"Support"}},{"@type":"WebPage","@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#webpage","url":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/","name":"Een voertuig onderscheppen | Rauwers Belgium","description":"Smart solutions for mobility and road safety | Een voertuig onderscheppen","inLanguage":"nl-NL","isPartOf":{"@id":"https:\/\/rauwers.be\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#breadcrumblist"},"author":{"@id":"https:\/\/rauwers.be\/nl\/author\/supportrauwerseurope-com\/#author"},"creator":{"@id":"https:\/\/rauwers.be\/nl\/author\/supportrauwerseurope-com\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/rauwers.be\/wp-content\/uploads\/2020\/03\/art-TS-famenne.jpg","@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#mainImage","width":1280,"height":800},"primaryImageOfPage":{"@id":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/#mainImage"},"datePublished":"2020-03-28T14:11:25+00:00","dateModified":"2023-05-28T17:00:03+00:00"},{"@type":"WebSite","@id":"https:\/\/rauwers.be\/nl\/#website","url":"https:\/\/rauwers.be\/nl\/","name":"Rauwers Belgium","description":"Smart solutions for mobility and road safety.","inLanguage":"nl-NL","publisher":{"@id":"https:\/\/rauwers.be\/nl\/#organization"}}]},"og:locale":"nl_NL","og:site_name":"Rauwers Belgium | Smart solutions for mobility and road safety.","og:type":"article","og:title":"Een voertuig onderscheppen | Rauwers Belgium","og:description":"Smart solutions for mobility and road safety | Een voertuig onderscheppen","og:url":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/","og:image":"https:\/\/rauwers.be\/wp-content\/uploads\/2021\/08\/logo_rauwers.svg","og:image:secure_url":"https:\/\/rauwers.be\/wp-content\/uploads\/2021\/08\/logo_rauwers.svg","article:published_time":"2020-03-28T14:11:25+00:00","article:modified_time":"2023-05-28T17:00:03+00:00","article:publisher":"https:\/\/www.facebook.com\/RauwersBelgium\/","twitter:card":"summary_large_image","twitter:title":"Een voertuig onderscheppen | Rauwers Belgium","twitter:description":"Smart solutions for mobility and road safety | Een voertuig onderscheppen","twitter:image":"https:\/\/rauwers.be\/wp-content\/uploads\/2021\/08\/logo_rauwers.svg"},"aioseo_meta_data":{"post_id":"2940","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-22 21:45:58","updated":"2025-07-25 02:20:50","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/rauwers.be\/nl\/\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/rauwers.be\/nl\/category\/artikels\/\" title=\"Artikels\">Artikels<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEen voertuig onderscheppen\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/rauwers.be\/nl\/"},{"label":"Artikels","link":"https:\/\/rauwers.be\/nl\/category\/artikels\/"},{"label":"Een voertuig onderscheppen","link":"https:\/\/rauwers.be\/nl\/een-voertuig-onderscheppen\/"}],"_links":{"self":[{"href":"https:\/\/rauwers.be\/nl\/wp-json\/wp\/v2\/posts\/2940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rauwers.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rauwers.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rauwers.be\/nl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/rauwers.be\/nl\/wp-json\/wp\/v2\/comments?post=2940"}],"version-history":[{"count":3,"href":"https:\/\/rauwers.be\/nl\/wp-json\/wp\/v2\/posts\/2940\/revisions"}],"predecessor-version":[{"id":18567,"href":"https:\/\/rauwers.be\/nl\/wp-json\/wp\/v2\/posts\/2940\/revisions\/18567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rauwers.be\/nl\/wp-json\/wp\/v2\/media\/15832"}],"wp:attachment":[{"href":"https:\/\/rauwers.be\/nl\/wp-json\/wp\/v2\/media?parent=2940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rauwers.be\/nl\/wp-json\/wp\/v2\/categories?post=2940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rauwers.be\/nl\/wp-json\/wp\/v2\/tags?post=2940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}